{"id":20690,"date":"2016-09-21T12:23:23","date_gmt":"2016-09-21T17:23:23","guid":{"rendered":"http:\/\/www.etrafficlane.com\/60dollarmiracle\/facebook-how-to-tag-or-mention-people-pages-or-groups"},"modified":"2016-09-21T12:23:46","modified_gmt":"2016-09-21T17:23:46","slug":"facebook-how-to-tag-or-mention-people-pages-or-groups","status":"publish","type":"post","link":"https:\/\/www.etrafficlane.com\/60dollarmiracle\/facebook-how-to-tag-or-mention-people-pages-or-groups","title":{"rendered":"Facebook &#8211; How To Tag Or Mention People, Pages Or Groups"},"content":{"rendered":"\n<p>[shock_spots id=&#8221;2700&#8243;]<br \/>\n<\/p>\n<p>[wp_rss_multi_importer]<br \/>\n<br \/>\nhttp:\/\/ezinearticles.com\/?Facebook&#8212;How-To-Tag-Or-Mention-People,-Pages-Or-Groups&#038;id=5073645<br \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[shock_spots id=&#8221;2700&#8243;] [wp_rss_multi_importer] http:\/\/ezinearticles.com\/?Facebook&#8212;How-To-Tag-Or-Mention-People,-Pages-Or-Groups&#038;id=5073645<\/p>\n","protected":false},"author":1288,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-20690","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/www.etrafficlane.com\/60dollarmiracle\/wp-json\/wp\/v2\/posts\/20690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.etrafficlane.com\/60dollarmiracle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.etrafficlane.com\/60dollarmiracle\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.etrafficlane.com\/60dollarmiracle\/wp-json\/wp\/v2\/users\/1288"}],"replies":[{"embeddable":true,"href":"https:\/\/www.etrafficlane.com\/60dollarmiracle\/wp-json\/wp\/v2\/comments?post=20690"}],"version-history":[{"count":0,"href":"https:\/\/www.etrafficlane.com\/60dollarmiracle\/wp-json\/wp\/v2\/posts\/20690\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.etrafficlane.com\/60dollarmiracle\/wp-json\/wp\/v2\/media?parent=20690"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.etrafficlane.com\/60dollarmiracle\/wp-json\/wp\/v2\/categories?post=20690"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.etrafficlane.com\/60dollarmiracle\/wp-json\/wp\/v2\/tags?post=20690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}