{"id":19826,"date":"2016-09-16T20:20:23","date_gmt":"2016-09-17T01:20:23","guid":{"rendered":"http:\/\/www.etrafficlane.com\/60dollarmiracle\/social-media-analytics-strategy-discovering-the-digital-media-strategy-blog"},"modified":"2016-09-16T20:20:23","modified_gmt":"2016-09-17T01:20:23","slug":"social-media-analytics-strategy-discovering-the-digital-media-strategy-blog","status":"publish","type":"post","link":"https:\/\/www.etrafficlane.com\/60dollarmiracle\/social-media-analytics-strategy-discovering-the-digital-media-strategy-blog","title":{"rendered":"Social media analytics strategy discovering | The Digital Media Strategy Blog"},"content":{"rendered":"<p><br \/>\n<a href=\"https:\/\/www.pinterest.com\/pin\/524669425321759094\"><img decoding=\"async\" src=\"https:\/\/s-media-cache-ak0.pinimg.com\/736x\/34\/d4\/6f\/34d46f1ca06743b3a56643175835666a.jpg\" title=\"Social media analytics strategy discovering | The Digital Media Strategy Blog\"><\/a><\/p>\n<p><a href=\"http:\/\/social-media-strategy-template.blogspot.com\/\" rel=\"nofollow\" target=\"_blank\">social-media-stra&#8230;<\/a> The perfect number of hashtags for each social media outlet pinterest, instagram, facebook, twitter<\/p>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.pinterest.com\/pin\/524669425321759094\">Source<\/a> by <a href=\"https:\/\/pinterest.com\/thedigitalmedia\">thedigitalmedia<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>social-media-stra&#8230; The perfect number of hashtags for each social media outlet pinterest, instagram, facebook, twitter Source by thedigitalmedia<\/p>\n","protected":false},"author":660,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-19826","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/www.etrafficlane.com\/60dollarmiracle\/wp-json\/wp\/v2\/posts\/19826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.etrafficlane.com\/60dollarmiracle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.etrafficlane.com\/60dollarmiracle\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.etrafficlane.com\/60dollarmiracle\/wp-json\/wp\/v2\/users\/660"}],"replies":[{"embeddable":true,"href":"https:\/\/www.etrafficlane.com\/60dollarmiracle\/wp-json\/wp\/v2\/comments?post=19826"}],"version-history":[{"count":0,"href":"https:\/\/www.etrafficlane.com\/60dollarmiracle\/wp-json\/wp\/v2\/posts\/19826\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.etrafficlane.com\/60dollarmiracle\/wp-json\/wp\/v2\/media?parent=19826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.etrafficlane.com\/60dollarmiracle\/wp-json\/wp\/v2\/categories?post=19826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.etrafficlane.com\/60dollarmiracle\/wp-json\/wp\/v2\/tags?post=19826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}